{"id":929,"date":"2023-01-13T13:38:31","date_gmt":"2023-01-13T13:38:31","guid":{"rendered":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/?post_type=person&#038;p=929"},"modified":"2026-04-17T12:54:18","modified_gmt":"2026-04-17T16:54:18","slug":"diego-chandia-jemenao","status":"publish","type":"person","link":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/diego-chandia-jemenao\/","title":{"rendered":"Diego  Galvez Jemenao"},"content":{"rendered":"<p>Abogado con amplia experiencia en tramitaci\u00f3n de causas civiles y laborales.<\/p>\n<p>Asimismo, cuenta con experiencia en asesor\u00eda de empresas en materias comerciales y\/o laborales.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":40,"featured_media":930,"template":"","people_tax":[],"class_list":["post-929","person","type-person","status-publish","has-post-thumbnail","hentry"],"email":"","tel_job":"","role":"","modal":"<div class=\"person-modal person-modal--scl\">\n<header class=\"person-modal__header\">\n<div class=\"person-modal__bg\"><\/div>\n<div class=\"modal-container\">\n<div class=\"person-modal__media\">\n\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-500x500.jpg\" class=\"person-modal__image wp-post-image\" alt=\"\" loading=\"lazy\" \/>\t\t\t<\/div>\n<div class=\"person-modal__data\">\n<h1 class=\"person-modal__name\">Diego  Galvez Jemenao<\/h1>\n<\/p><\/div>\n<\/p><\/div>\n<\/header>\n<div class=\"modal-container\">\n<div class=\"person-modal__content text\">\n<ul>\n<li>Abogado, Universidad Andr\u00e9s Bello<\/li>\n<li>Curso de destrezas y t\u00e9cnicas de litigaci\u00f3n oral en materia laboral impartido por California Western School of Law <\/li>\n<\/ul>\n<p>Abogado con amplia experiencia en tramitaci\u00f3n de causas civiles y laborales.<\/p>\n<p>Asimismo, cuenta con experiencia en asesor\u00eda de empresas en materias comerciales y\/o laborales.<\/p>\n<p>&nbsp;<\/p>\n<p>Abogado con amplia experiencia en tramitaci\u00f3n de causas civiles y laborales.<\/p>\n<p>Asimismo, cuenta con experiencia en asesor\u00eda de empresas en materias comerciales y\/o laborales.<\/p>\n<p>&nbsp;<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","_links":{"self":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/people\/929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/types\/person"}],"author":[{"embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/users\/40"}],"version-history":[{"count":1,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/people\/929\/revisions"}],"predecessor-version":[{"id":1619,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/people\/929\/revisions\/1619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/media?parent=929"}],"wp:term":[{"taxonomy":"people_tax","embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/people_tax?post=929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}