{"id":116,"date":"2014-06-23T19:52:05","date_gmt":"2014-06-23T19:52:05","guid":{"rendered":"http:\/\/derecho-scl.udd.cl\/clinica-juridica\/?page_id=116"},"modified":"2026-05-07T16:41:58","modified_gmt":"2026-05-07T20:41:58","slug":"equipo","status":"publish","type":"page","link":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/sobre-la-clinica-juridica\/equipo\/","title":{"rendered":"Equipo"},"content":{"rendered":"<!-- WP Block: UDD - People -->\n<section class=\"wp-block-udd-people \">\n\t<div class=\"container\">\n\t\t\t\t<header class=\"block__header\">\n\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\"><\/h2>\n\t\t\t\t\t\t\t\t<\/header>\n\t\t\t\t<div class=\"people-cards\">\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/mabel-dastres-abarca-2\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"572\"\n\t\tdata-postid=\"572\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-500x500.jpeg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-500x500.jpeg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-300x300.jpeg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-150x150.jpeg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-768x768.jpeg 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-62x62.jpeg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-750x750.jpeg 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-250x250.jpeg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-126x126.jpeg 126w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025.jpeg 853w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Mabel Dastres Abarca<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Directora Cl\u00ednica Jur\u00eddica<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/ximena-medina-2\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"416\"\n\t\tdata-postid=\"416\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-500x500.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-500x500.jpg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-300x300.jpg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-250x250.jpg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-126x126.jpg 126w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_.jpg 694w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Ximena  Medina Santis<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Coordinadora de Cl\u00ednica Jur\u00eddica<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<!-- WP Block: UDD - People -->\n<section class=\"wp-block-udd-people \">\n\t<div class=\"container\">\n\t\t\t\t<header class=\"block__header\">\n\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\">PROFESORES <\/h2>\n\t\t\t\t\t\t\t\t<\/header>\n\t\t\t\t<div class=\"people-cards\">\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/sara-vargas-carvajal\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"570\"\n\t\tdata-postid=\"570\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"321\" height=\"294\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2.jpg 321w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2-300x275.jpg 300w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Sara  Vargas Carvajal<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/karl-roland-sievers-jaschan\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"409\"\n\t\tdata-postid=\"409\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"200\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/karl-st.byn1_.png\" class=\"person-card__image wp-post-image\" alt=\"\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Karl Roland Sievers Jaschan<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/sebastian-serey-gaggero\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"1103\"\n\t\tdata-postid=\"1103\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-500x500.png\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-500x500.png 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-300x300.png 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-1024x1024.png 1024w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-150x150.png 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-768x768.png 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-62x62.png 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-1536x1536.png 1536w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-2048x2048.png 2048w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-750x750.png 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-250x250.png 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/11\/sebastian-serey-126x126.png 126w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Sebasti\u00e1n  Serey Gaggero<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/hernan-hidalgo-gomez\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"414\"\n\t\tdata-postid=\"414\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/hernan-hidalgo-gomez.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/hernan-hidalgo-gomez.jpg 200w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/hernan-hidalgo-gomez-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/hernan-hidalgo-gomez-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/hernan-hidalgo-gomez-126x126.jpg 126w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Hern\u00e1n  Hidalgo G\u00f3mez<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/felipe-utman-suarez\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"124\"\n\t\tdata-postid=\"124\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2015\/09\/felipe-utman.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2015\/09\/felipe-utman.jpg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2015\/09\/felipe-utman-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2015\/09\/felipe-utman-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2015\/09\/felipe-utman-126x126.jpg 126w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Felipe Utman Su\u00e1rez<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/simon-ponce-riquelme\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"569\"\n\t\tdata-postid=\"569\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"453\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce.jpg 402w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce-266x300.jpg 266w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Sim\u00f3n  Ponce Riquelme<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/mabel-dastres-abarca\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"115\"\n\t\tdata-postid=\"115\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-500x500.jpeg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-500x500.jpeg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-300x300.jpeg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-150x150.jpeg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-768x768.jpeg 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-62x62.jpeg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-750x750.jpeg 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-250x250.jpeg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025-126x126.jpeg 126w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2021\/06\/mabel11-2025.jpeg 853w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Mabel Dastres Abarca<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/ximena-medina\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"412\"\n\t\tdata-postid=\"412\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-500x500.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-500x500.jpg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-300x300.jpg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-250x250.jpg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_-126x126.jpg 126w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/ximena-medina-2025-byn_.jpg 694w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Ximena  Medina Santis<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/gonzalo-guzman-2\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"573\"\n\t\tdata-postid=\"573\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"478\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman.jpg 1316w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-300x287.jpg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-1024x978.jpg 1024w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-768x734.jpg 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-960x917.jpg 960w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Gonzalo  Guzm\u00e1n<\/h3>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<!-- WP Block: UDD - People -->\n<section class=\"wp-block-udd-people \">\n\t<div class=\"container\">\n\t\t\t\t<header class=\"block__header\">\n\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\">Abogados Asistentes<\/h2>\n\t\t\t\t\t\t\t\t<\/header>\n\t\t\t\t<div class=\"people-cards\">\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/catalina-vallejos-sanchez\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"1495\"\n\t\tdata-postid=\"1495\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-500x500.png\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-500x500.png 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-300x300.png 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-1024x1024.png 1024w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-150x150.png 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-768x768.png 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-62x62.png 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-750x750.png 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-250x250.png 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos-126x126.png 126w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/catalina-vallejos.png 1042w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Catalina  Vallejos S\u00e1nchez<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/nicolas-romero-fuentealba\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"1497\"\n\t\tdata-postid=\"1497\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-500x500.png\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-500x500.png 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-150x150.png 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-62x62.png 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-250x250.png 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2024\/09\/nicolas-romero-126x126.png 126w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Nicol\u00e1s  Romero Fuentealba<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/daniela-sepulveda-vargas\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"1594\"\n\t\tdata-postid=\"1594\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-500x500.png\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-500x500.png 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-150x150.png 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-62x62.png 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-750x750.png 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-250x250.png 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2025\/05\/daniela-sepulveda-126x126.png 126w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Daniela  Sep\u00falveda Vargas<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/diego-chandia-jemenao\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"929\"\n\t\tdata-postid=\"929\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-500x500.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-500x500.jpg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-750x750.jpg 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-250x250.jpg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/diego-chandia-126x126.jpg 126w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Diego  Galvez Jemenao<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/simon-ponce-riquelme\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"569\"\n\t\tdata-postid=\"569\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"453\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce.jpg 402w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2019\/03\/Simon-Ponce-266x300.jpg 266w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Sim\u00f3n  Ponce Riquelme<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/sara-vargas-carvajal\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"570\"\n\t\tdata-postid=\"570\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"321\" height=\"294\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2.jpg 321w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Foto-sara-CV-2-300x275.jpg 300w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Sara  Vargas Carvajal<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/gonzalo-guzman-2\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"573\"\n\t\tdata-postid=\"573\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"478\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman.jpg 1316w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-300x287.jpg 300w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-1024x978.jpg 1024w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-768x734.jpg 768w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2020\/05\/Gonzalo.Guzman-960x917.jpg 960w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Gonzalo  Guzm\u00e1n<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Abogado Asistente<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<!-- WP Block: UDD - People -->\n<section class=\"wp-block-udd-people \">\n\t<div class=\"container\">\n\t\t\t\t<header class=\"block__header\">\n\t\t\t\t\t\t\t\n<h2 class=\"wp-block-heading\">ASISTENTE JUR\u00cdDICO<\/h2>\n\t\t\t\t\t\t\t\t<\/header>\n\t\t\t\t<div class=\"people-cards\">\n\t\t\t\t\t<div class=\"person-card\">\n\t<a href=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/persona\/roxana-avila-orellana\/\"\n\t\tclass=\"person-card__inner js-person-modal\"\n\t\tdata-post-id=\"931\"\n\t\tdata-postid=\"931\"\n\t>\n\t\t\t<div class=\"person-card__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-500x500.jpg\" class=\"person-card__image wp-post-image\" alt=\"\" srcset=\"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-500x500.jpg 500w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-150x150.jpg 150w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-62x62.jpg 62w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-750x750.jpg 750w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-250x250.jpg 250w, https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/files\/2023\/01\/roxana-avila-126x126.jpg 126w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t<\/div>\n\t\t\t<div class=\"person-card__content\">\n\t\t\t<h3 class=\"person-card__name\">Roxana  \u00c1vila Orellana<\/h3>\n\t\t\t\t\t<span class=\"person-card__description\">Asistente Jur\u00eddico<\/span>\n\t\t\t\t\t<span class=\"person-card__cta\">Ver perfil<\/span>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":15,"featured_media":0,"parent":47,"menu_order":1,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-116","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/pages\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":41,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/pages\/116\/revisions"}],"predecessor-version":[{"id":1635,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/pages\/116\/revisions\/1635"}],"up":[{"embeddable":true,"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/pages\/47"}],"wp:attachment":[{"href":"https:\/\/derecho.udd.cl\/clinica-juridica-santiago\/wp-json\/wp\/v2\/media?parent=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}